{"id":647,"count":4,"description":"Blog dell\u2019Azienda Agricola Familiare Rakovac","link":"https:\/\/opg-rakovac.hr\/it\/category\/blog\/","name":"Blog","slug":"blog","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blog sull\u2019olio extravergine d\u2019oliva | OPG Rakovac<\/title>\n<meta name=\"description\" content=\"Nel nostro blog scoprite tutto sull\u2019olio extravergine d\u2019oliva \u2013 di prima mano: dal produttore dell\u2019olio extravergine d\u2019oliva Bilini.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog sull\u2019olio extravergine d\u2019oliva | OPG Rakovac\" \/>\n<meta property=\"og:description\" content=\"Nel nostro blog scoprite tutto sull\u2019olio extravergine d\u2019oliva \u2013 di prima mano: dal produttore dell\u2019olio extravergine d\u2019oliva Bilini.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opg-rakovac.hr\/it\/category\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"OPG Rakovac\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2018\/05\/featured-img.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/category\\\/blog\\\/\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/category\\\/blog\\\/\",\"name\":\"Blog sull\u2019olio extravergine d\u2019oliva | OPG Rakovac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/#website\"},\"description\":\"Nel nostro blog scoprite tutto sull\u2019olio extravergine d\u2019oliva \u2013 di prima mano: dal produttore dell\u2019olio extravergine d\u2019oliva Bilini.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/category\\\/blog\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/category\\\/blog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/\",\"name\":\"OPG Rakovac\",\"description\":\"Istarsko ekstra djevi\u010dansko maslinovo ulje Bilini\",\"publisher\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/#organization\",\"name\":\"OPG Rakovac\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/favicon.png\",\"width\":200,\"height\":200,\"caption\":\"OPG Rakovac\"},\"image\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ekstra.djevicansko.maslinovo.ulje.Bilini\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bilini_maslinovo_ulje\\\/\",\"https:\\\/\\\/hr.linkedin.com\\\/in\\\/bilini\",\"https:\\\/\\\/www.pinterest.com\\\/Bilini_OliveOil\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7hfzAtwp1YOvhlmwNYkyQw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog sull\u2019olio extravergine d\u2019oliva | OPG Rakovac","description":"Nel nostro blog scoprite tutto sull\u2019olio extravergine d\u2019oliva \u2013 di prima mano: dal produttore dell\u2019olio extravergine d\u2019oliva Bilini.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Blog sull\u2019olio extravergine d\u2019oliva | OPG Rakovac","og_description":"Nel nostro blog scoprite tutto sull\u2019olio extravergine d\u2019oliva \u2013 di prima mano: dal produttore dell\u2019olio extravergine d\u2019oliva Bilini.","og_url":"https:\/\/opg-rakovac.hr\/it\/category\/blog\/","og_site_name":"OPG Rakovac","og_image":[{"width":1200,"height":630,"url":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2018\/05\/featured-img.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/opg-rakovac.hr\/it\/category\/blog\/","url":"https:\/\/opg-rakovac.hr\/it\/category\/blog\/","name":"Blog sull\u2019olio extravergine d\u2019oliva | OPG Rakovac","isPartOf":{"@id":"https:\/\/opg-rakovac.hr\/it\/#website"},"description":"Nel nostro blog scoprite tutto sull\u2019olio extravergine d\u2019oliva \u2013 di prima mano: dal produttore dell\u2019olio extravergine d\u2019oliva Bilini.","breadcrumb":{"@id":"https:\/\/opg-rakovac.hr\/it\/category\/blog\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/opg-rakovac.hr\/it\/category\/blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/opg-rakovac.hr\/it\/"},{"@type":"ListItem","position":2,"name":"Blog"}]},{"@type":"WebSite","@id":"https:\/\/opg-rakovac.hr\/it\/#website","url":"https:\/\/opg-rakovac.hr\/it\/","name":"OPG Rakovac","description":"Istarsko ekstra djevi\u010dansko maslinovo ulje Bilini","publisher":{"@id":"https:\/\/opg-rakovac.hr\/it\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/opg-rakovac.hr\/it\/#organization","name":"OPG Rakovac","url":"https:\/\/opg-rakovac.hr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/opg-rakovac.hr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2015\/12\/favicon.png","contentUrl":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2015\/12\/favicon.png","width":200,"height":200,"caption":"OPG Rakovac"},"image":{"@id":"https:\/\/opg-rakovac.hr\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ekstra.djevicansko.maslinovo.ulje.Bilini\/","https:\/\/www.instagram.com\/bilini_maslinovo_ulje\/","https:\/\/hr.linkedin.com\/in\/bilini","https:\/\/www.pinterest.com\/Bilini_OliveOil\/","https:\/\/www.youtube.com\/channel\/UC7hfzAtwp1YOvhlmwNYkyQw"]}]}},"_links":{"self":[{"href":"https:\/\/opg-rakovac.hr\/it\/wp-json\/wp\/v2\/categories\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opg-rakovac.hr\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/opg-rakovac.hr\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/opg-rakovac.hr\/it\/wp-json\/wp\/v2\/posts?categories=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}