{"id":8418,"date":"2016-05-01T08:46:51","date_gmt":"2016-05-01T08:46:51","guid":{"rendered":"https:\/\/opg-rakovac.hr\/2018\/ulika-2016-zlato-za-bilini\/"},"modified":"2018-07-06T20:28:26","modified_gmt":"2018-07-06T20:28:26","slug":"ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini","status":"publish","type":"post","link":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/","title":{"rendered":"Ulika 2016"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5624,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-nagrada.php","format":"standard","meta":{"_acf_changed":false,"h5ap_radio_sources":[],"footnotes":""},"categories":[413],"tags":[444,608,610],"class_list":["post-8418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auszeichnungen","tag-bilini-de","tag-medulin-de","tag-ulika-2016-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ulika 2016 Medulin - Gold f\u00fcr Oliven\u00f6l extra vergine Bilini!<\/title>\n<meta name=\"description\" content=\"Familienbauernhof Rakovac gewann eine weitere Goldmedaille f\u00fcr sein Oliven\u00f6l extra vergine Bilini - dieses Mal auf der Ulika 2016 in Medulin\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ulika 2016 Medulin - Gold f\u00fcr Oliven\u00f6l extra vergine Bilini!\" \/>\n<meta property=\"og:description\" content=\"Familienbauernhof Rakovac gewann eine weitere Goldmedaille f\u00fcr sein Oliven\u00f6l extra vergine Bilini - dieses Mal auf der Ulika 2016 in Medulin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/\" \/>\n<meta property=\"og:site_name\" content=\"OPG Rakovac\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ekstra.djevicansko.maslinovo.ulje.Bilini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-01T08:46:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-06T20:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2016\/05\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sa\u0161a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sa\u0161a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/\"},\"author\":{\"name\":\"Sa\u0161a\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#\\\/schema\\\/person\\\/144d2cd7fe877474e322c4ffe1ea30d7\"},\"headline\":\"Ulika 2016\",\"datePublished\":\"2016-05-01T08:46:51+00:00\",\"dateModified\":\"2018-07-06T20:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg\",\"keywords\":[\"bilini\",\"medulin\",\"ulika 2016\"],\"articleSection\":[\"Auszeichnungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/\",\"name\":\"Ulika 2016 Medulin - Gold f\u00fcr Oliven\u00f6l extra vergine Bilini!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg\",\"datePublished\":\"2016-05-01T08:46:51+00:00\",\"dateModified\":\"2018-07-06T20:28:26+00:00\",\"description\":\"Familienbauernhof Rakovac gewann eine weitere Goldmedaille f\u00fcr sein Oliven\u00f6l extra vergine Bilini - dieses Mal auf der Ulika 2016 in Medulin\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg\",\"contentUrl\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg\",\"width\":950,\"height\":501,\"caption\":\"Oliven\u00f6l extra vergine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/auszeichnungen\\\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ulika 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/\",\"name\":\"OPG Rakovac\",\"description\":\"Istarsko ekstra djevi\u010dansko maslinovo ulje Bilini\",\"publisher\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#organization\",\"name\":\"OPG Rakovac\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/opg-rakovac.hr\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/favicon.png\",\"width\":200,\"height\":200,\"caption\":\"OPG Rakovac\"},\"image\":{\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ekstra.djevicansko.maslinovo.ulje.Bilini\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bilini_maslinovo_ulje\\\/\",\"https:\\\/\\\/hr.linkedin.com\\\/in\\\/bilini\",\"https:\\\/\\\/www.pinterest.com\\\/Bilini_OliveOil\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7hfzAtwp1YOvhlmwNYkyQw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/#\\\/schema\\\/person\\\/144d2cd7fe877474e322c4ffe1ea30d7\",\"name\":\"Sa\u0161a\",\"description\":\"Vedrana is the owner of our family farm. But I am sheer power! :) The guy who does all the physical work in olive groves with a little help of my friends (tractors). :)\",\"sameAs\":[\"https:\\\/\\\/opg-rakovac.hr\"],\"url\":\"https:\\\/\\\/opg-rakovac.hr\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ulika 2016 Medulin - Gold f\u00fcr Oliven\u00f6l extra vergine Bilini!","description":"Familienbauernhof Rakovac gewann eine weitere Goldmedaille f\u00fcr sein Oliven\u00f6l extra vergine Bilini - dieses Mal auf der Ulika 2016 in Medulin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/","og_locale":"de_DE","og_type":"article","og_title":"Ulika 2016 Medulin - Gold f\u00fcr Oliven\u00f6l extra vergine Bilini!","og_description":"Familienbauernhof Rakovac gewann eine weitere Goldmedaille f\u00fcr sein Oliven\u00f6l extra vergine Bilini - dieses Mal auf der Ulika 2016 in Medulin","og_url":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/","og_site_name":"OPG Rakovac","article_publisher":"https:\/\/www.facebook.com\/Ekstra.djevicansko.maslinovo.ulje.Bilini\/","article_published_time":"2016-05-01T08:46:51+00:00","article_modified_time":"2018-07-06T20:28:26+00:00","og_image":[{"width":950,"height":501,"url":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2016\/05\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg","type":"image\/jpeg"}],"author":"Sa\u0161a","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sa\u0161a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#article","isPartOf":{"@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/"},"author":{"name":"Sa\u0161a","@id":"https:\/\/opg-rakovac.hr\/de\/#\/schema\/person\/144d2cd7fe877474e322c4ffe1ea30d7"},"headline":"Ulika 2016","datePublished":"2016-05-01T08:46:51+00:00","dateModified":"2018-07-06T20:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/opg-rakovac.hr\/de\/#organization"},"image":{"@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#primaryimage"},"thumbnailUrl":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2016\/05\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg","keywords":["bilini","medulin","ulika 2016"],"articleSection":["Auszeichnungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/","url":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/","name":"Ulika 2016 Medulin - Gold f\u00fcr Oliven\u00f6l extra vergine Bilini!","isPartOf":{"@id":"https:\/\/opg-rakovac.hr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#primaryimage"},"image":{"@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#primaryimage"},"thumbnailUrl":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2016\/05\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg","datePublished":"2016-05-01T08:46:51+00:00","dateModified":"2018-07-06T20:28:26+00:00","description":"Familienbauernhof Rakovac gewann eine weitere Goldmedaille f\u00fcr sein Oliven\u00f6l extra vergine Bilini - dieses Mal auf der Ulika 2016 in Medulin","breadcrumb":{"@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#primaryimage","url":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2016\/05\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg","contentUrl":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2016\/05\/Ulika-2016-OPG-Rakovac-Zlatna-medalja.jpg","width":950,"height":501,"caption":"Oliven\u00f6l extra vergine"},{"@type":"BreadcrumbList","@id":"https:\/\/opg-rakovac.hr\/de\/auszeichnungen\/ulika-2016-gold-fuer-olivenoel-extra-vergine-bilini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/opg-rakovac.hr\/de\/"},{"@type":"ListItem","position":2,"name":"Ulika 2016"}]},{"@type":"WebSite","@id":"https:\/\/opg-rakovac.hr\/de\/#website","url":"https:\/\/opg-rakovac.hr\/de\/","name":"OPG Rakovac","description":"Istarsko ekstra djevi\u010dansko maslinovo ulje Bilini","publisher":{"@id":"https:\/\/opg-rakovac.hr\/de\/#organization"},"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/opg-rakovac.hr\/de\/#organization","name":"OPG Rakovac","url":"https:\/\/opg-rakovac.hr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/opg-rakovac.hr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2015\/12\/favicon.png","contentUrl":"https:\/\/opg-rakovac.hr\/wp-content\/uploads\/2015\/12\/favicon.png","width":200,"height":200,"caption":"OPG Rakovac"},"image":{"@id":"https:\/\/opg-rakovac.hr\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ekstra.djevicansko.maslinovo.ulje.Bilini\/","https:\/\/www.instagram.com\/bilini_maslinovo_ulje\/","https:\/\/hr.linkedin.com\/in\/bilini","https:\/\/www.pinterest.com\/Bilini_OliveOil\/","https:\/\/www.youtube.com\/channel\/UC7hfzAtwp1YOvhlmwNYkyQw"]},{"@type":"Person","@id":"https:\/\/opg-rakovac.hr\/de\/#\/schema\/person\/144d2cd7fe877474e322c4ffe1ea30d7","name":"Sa\u0161a","description":"Vedrana is the owner of our family farm. But I am sheer power! :) The guy who does all the physical work in olive groves with a little help of my friends (tractors). :)","sameAs":["https:\/\/opg-rakovac.hr"],"url":"https:\/\/opg-rakovac.hr\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/posts\/8418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/comments?post=8418"}],"version-history":[{"count":4,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/posts\/8418\/revisions"}],"predecessor-version":[{"id":9548,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/posts\/8418\/revisions\/9548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/media\/5624"}],"wp:attachment":[{"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/media?parent=8418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/categories?post=8418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/opg-rakovac.hr\/de\/wp-json\/wp\/v2\/tags?post=8418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}